{"id":23,"date":"2025-01-07T20:40:07","date_gmt":"2025-01-07T20:40:07","guid":{"rendered":"https:\/\/telemedicina-life.ar\/blog\/?p=23"},"modified":"2025-01-07T20:45:18","modified_gmt":"2025-01-07T20:45:18","slug":"como-combatir-la-crisis-de-la-salud-mental-en-el-trabajo","status":"publish","type":"post","link":"https:\/\/telemedicina-life.ar\/blog\/como-combatir-la-crisis-de-la-salud-mental-en-el-trabajo\/","title":{"rendered":"C\u00f3mo combatir la crisis de la salud mental en el trabajo"},"content":{"rendered":"<header class=\"nav-down nav-transparent\">\n<div class=\"bar2\"><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div class=\"logo\">Seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), la ansiedad y la depresi\u00f3n provocan la perdida de unos 12.000 mil millones de d\u00edas laborables, lo que representa un costo global de 1 bill\u00f3n de d\u00f3lares.<\/div>\n<\/header>\n<article>\n<div id=\"article-container\" class=\"container\">\n<div class=\"body\">\n<div class=\"author-date\">\n<div class=\"date\"><\/div>\n<\/div>\n<p>La<strong>\u00a0<a href=\"http:\/\/www.telemedicina-life.ar\">salud mental<\/a>\u00a0<\/strong>se convirti\u00f3\u00a0en uno de los<strong>\u00a0desaf\u00edos m\u00e1s importantes\u00a0para las empresas en todo el mundo.\u00a0<\/strong>Seg\u00fan la\u00a0<strong>Organizaci\u00f3n Mundial de la Salud (OMS)<\/strong>, la\u00a0<strong>ansiedad y la depresi\u00f3n provocan la perdida de unos 12.000 mil millones de d\u00edas laborables<\/strong>, lo que representa un costo global de 1 bill\u00f3n de d\u00f3lares.<\/p>\n<p>Seg\u00fan los expertos, los factores que agravan esta<strong>\u00a0crisis van desde el encarecimiento del costo de vida\u00a0<\/strong>hasta la influencia de las redes sociales.\u00a0En este contexto, los l\u00edderes empresariales comienzan a\u00a0<strong>priorizar el <a href=\"https:\/\/telemedicina-life.ar\/registrarse.html\">bienestar emocional<\/a> de sus empleados.<\/strong><\/p>\n<p>La empresa multinacional\u00a0<em>MindForward Alliance<\/em>\u00a0realiz\u00f3 una<strong>\u00a0encuesta entre 12.200 trabajadores.<\/strong><\/p>\n<p><iframe class=\"i-amphtml-fill-content\" src=\"https:\/\/rudo.video\/vod\/dTlasNpbf7jg?volume=0#amp=1\" name=\"amp_iframe0\" frameborder=\"0\" sandbox=\"allow-scripts allow-same-origin\" data-mce-fragment=\"1\"><\/iframe>Algunas de las conclusiones fueron que los\u00a0<strong>problemas de salud mental son m\u00e1s comunes dentro las compa\u00f1\u00edas<\/strong>\u00a0de servicios financieros y firmas de abogados.<\/p>\n<p>A su vez, el estudio marc\u00f3 que cuando los ejecutivos de las empresas tratan el\u00a0<strong>tema de salud mental en el lugar de trabajo<\/strong>, un 85% de sus trabajadores se sent\u00edan apoyados.<\/p>\n<p>Cuando el problema es ignorado o evitado por los ejecutivos, tan s\u00f3lo un<strong>\u00a031% sent\u00eda contenci\u00f3n.<\/strong><\/p>\n<p>En ese sentido algunas compa\u00f1\u00edas comienzan a<strong>\u00a0implementar reuniones semanales con coaches y equipos especializados en salud mental<\/strong>, lo que redujo\u00a0la\u00a0<strong>rotaci\u00f3n de personal, el ausentismo<\/strong>\u00a0y mejor\u00f3\u00a0la productividad en un 40 y 60%.<\/p>\n<\/div>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), la ansiedad y la depresi\u00f3n provocan la perdida de unos 12.000 mil millones de d\u00edas laborables, lo que representa un costo global de 1 bill\u00f3n de&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":24,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[4],"tags":[10,5,8,9,7,6],"class_list":["post-23","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-bienestar-corporativo","tag-ansiedad-laboral","tag-estres-laboral","tag-psicologia","tag-psicologia-online","tag-salud-mental","tag-telemedicina-argentina","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/telemedicina-life.ar\/blog\/wp-json\/wp\/v2\/posts\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/telemedicina-life.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/telemedicina-life.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/telemedicina-life.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/telemedicina-life.ar\/blog\/wp-json\/wp\/v2\/comments?post=23"}],"version-history":[{"count":2,"href":"https:\/\/telemedicina-life.ar\/blog\/wp-json\/wp\/v2\/posts\/23\/revisions"}],"predecessor-version":[{"id":26,"href":"https:\/\/telemedicina-life.ar\/blog\/wp-json\/wp\/v2\/posts\/23\/revisions\/26"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/telemedicina-life.ar\/blog\/wp-json\/wp\/v2\/media\/24"}],"wp:attachment":[{"href":"https:\/\/telemedicina-life.ar\/blog\/wp-json\/wp\/v2\/media?parent=23"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/telemedicina-life.ar\/blog\/wp-json\/wp\/v2\/categories?post=23"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/telemedicina-life.ar\/blog\/wp-json\/wp\/v2\/tags?post=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}